{"id":4883,"date":"2022-02-01T13:00:00","date_gmt":"2022-02-01T12:00:00","guid":{"rendered":"https:\/\/derogee-it.nl\/?p=4883"},"modified":"2024-02-09T09:11:10","modified_gmt":"2024-02-09T08:11:10","slug":"sander-architects-implementations-and-it-maitenance","status":"publish","type":"post","link":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/","title":{"rendered":"Sander Architects &#8211; Implementations and IT maitenance"},"content":{"rendered":"<div id=\"pl-4883\"  class=\"panel-layout\" ><div id=\"pg-4883-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-4883-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-4883-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>We handled the server migrations for Sander Architects. Thanks to this migration, the organization is running on a solid and 'future-proof' platform. In addition, a remote working solution has been implemented. Employees can now access the systems anytime and anywhere.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>We handled the server migrations for Sander Architects. Thanks to this migration, the organization is running on a solid and &#8216;future-proof&#8217; platform. In addition, a remote working solution has been implemented. Employees can now access the systems anytime and anywhere.<\/p>\n","protected":false},"author":1,"featured_media":4707,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[266,262],"tags":[],"class_list":["post-4883","post","type-post","status-publish","format-standard","has-post-thumbnail","category-implementations","category-other","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.\" \/>\n<meta property=\"og:description\" content=\"We handled the server migrations for Sander Architects. Thanks to this migration, the organization is running on a solid and &#039;future-proof&#039; platform. In addition, a remote working solution has been implemented. Employees can now access the systems anytime and anywhere.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/\" \/>\n<meta property=\"og:site_name\" content=\"Derogee IT Consultants B.V.\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T08:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"162\" \/>\n\t<meta property=\"og:image:height\" content=\"98\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Probu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Probu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/\"},\"author\":{\"name\":\"Probu\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/#\\\/schema\\\/person\\\/fac2dafd47e1e76514afbd29d5d43d6e\"},\"headline\":\"Sander Architects &#8211; Implementations and IT maitenance\",\"datePublished\":\"2022-02-01T12:00:00+00:00\",\"dateModified\":\"2024-02-09T08:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/\"},\"wordCount\":47,\"image\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/derogee-it.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/sander-architecten.gif\",\"articleSection\":[\"Implementations\",\"Other\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/\",\"url\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/\",\"name\":\"Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/derogee-it.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/sander-architecten.gif\",\"datePublished\":\"2022-02-01T12:00:00+00:00\",\"dateModified\":\"2024-02-09T08:11:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/#\\\/schema\\\/person\\\/fac2dafd47e1e76514afbd29d5d43d6e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/derogee-it.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/sander-architecten.gif\",\"contentUrl\":\"https:\\\/\\\/derogee-it.nl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/sander-architecten.gif\",\"width\":162,\"height\":98},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/other\\\/sander-architects-implementations-and-it-maitenance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sander Architects &#8211; Implementations and IT maitenance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/#website\",\"url\":\"https:\\\/\\\/derogee-it.nl\\\/\",\"name\":\"Derogee IT Consultants B.V.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/derogee-it.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/derogee-it.nl\\\/#\\\/schema\\\/person\\\/fac2dafd47e1e76514afbd29d5d43d6e\",\"name\":\"Probu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g\",\"caption\":\"Probu\"},\"url\":\"https:\\\/\\\/derogee-it.nl\\\/en\\\/author\\\/probu-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/","og_locale":"en_US","og_type":"article","og_title":"Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.","og_description":"We handled the server migrations for Sander Architects. Thanks to this migration, the organization is running on a solid and 'future-proof' platform. In addition, a remote working solution has been implemented. Employees can now access the systems anytime and anywhere.","og_url":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/","og_site_name":"Derogee IT Consultants B.V.","article_published_time":"2022-02-01T12:00:00+00:00","article_modified_time":"2024-02-09T08:11:10+00:00","og_image":[{"width":162,"height":98,"url":"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif","type":"image\/gif"}],"author":"Probu","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Probu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#article","isPartOf":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/"},"author":{"name":"Probu","@id":"https:\/\/derogee-it.nl\/#\/schema\/person\/fac2dafd47e1e76514afbd29d5d43d6e"},"headline":"Sander Architects &#8211; Implementations and IT maitenance","datePublished":"2022-02-01T12:00:00+00:00","dateModified":"2024-02-09T08:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/"},"wordCount":47,"image":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#primaryimage"},"thumbnailUrl":"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif","articleSection":["Implementations","Other"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/","url":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/","name":"Sander Architects - Implementations and IT maitenance - Derogee IT Consultants B.V.","isPartOf":{"@id":"https:\/\/derogee-it.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#primaryimage"},"image":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#primaryimage"},"thumbnailUrl":"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif","datePublished":"2022-02-01T12:00:00+00:00","dateModified":"2024-02-09T08:11:10+00:00","author":{"@id":"https:\/\/derogee-it.nl\/#\/schema\/person\/fac2dafd47e1e76514afbd29d5d43d6e"},"breadcrumb":{"@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#primaryimage","url":"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif","contentUrl":"https:\/\/derogee-it.nl\/wp-content\/uploads\/2023\/04\/sander-architecten.gif","width":162,"height":98},{"@type":"BreadcrumbList","@id":"https:\/\/derogee-it.nl\/en\/other\/sander-architects-implementations-and-it-maitenance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/derogee-it.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Sander Architects &#8211; Implementations and IT maitenance"}]},{"@type":"WebSite","@id":"https:\/\/derogee-it.nl\/#website","url":"https:\/\/derogee-it.nl\/","name":"Derogee IT Consultants B.V.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/derogee-it.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/derogee-it.nl\/#\/schema\/person\/fac2dafd47e1e76514afbd29d5d43d6e","name":"Probu","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0bc355f410aaf8d1f7f39b1cdd8079d1622b2fba7e6d284c765a29f31ff4f51?s=96&d=mm&r=g","caption":"Probu"},"url":"https:\/\/derogee-it.nl\/en\/author\/probu-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/posts\/4883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/comments?post=4883"}],"version-history":[{"count":0,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/posts\/4883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/media\/4707"}],"wp:attachment":[{"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/media?parent=4883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/categories?post=4883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/derogee-it.nl\/en\/wp-json\/wp\/v2\/tags?post=4883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}